{"id":823,"date":"2008-05-04T21:42:36","date_gmt":"2008-05-04T19:42:36","guid":{"rendered":"http:\/\/w-jugend.tsv-birkenau.de\/index.php\/archives\/823"},"modified":"2009-05-18T13:52:00","modified_gmt":"2009-05-18T11:52:00","slug":"oberliga-quali-der-a-jugend-in-birkenau","status":"publish","type":"post","link":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/archives\/823","title":{"rendered":"A-Jugend souver\u00e4n f\u00fcr die Oberliga qualifiziert"},"content":{"rendered":"<p><img decoding=\"async\" width=\"400\" src=\"http:\/\/w-jugend.tsv-birkenau.de\/wp-content\/upload\/aj_quali_paddy.jpg\" alt=\"aj_quali_paddy.jpg\" \/><\/p>\n<p>Die weibliche A-Jugend des TSV Birkenau konnte sich am Sonntag, 04. Mai 2008,\u00a0 beim Qualifikationsturnier in Birkenau erneut f\u00fcr die Oberliga qualifizieren. <!--more--><br \/>\nMit dem gro\u00dfen Ziel vor Augen, n\u00e4chste Runde in der BWOL spielen zu k\u00f6nnen, begannen die A-M\u00e4dels im ersten Spiel gegen die SG Leutershausen \u00e4u\u00dferst engagiert. Bereits nach 15 Minuten leuchtete der Zwischenstand von 14:03 f\u00fcr Birkenau auf der Anzeigetafel. Am Ende stand mit 22:06 ein unerwartet deutlicher Sieg zu Buche.<\/p>\n<p>Auch im 2. Spiel gegen die HSG Hemsbach\/Sulzbach lie\u00dfen die Birkenauerinnen beim 14:06-Sieg nichts anbrennen. Schon nach 13 Minuten stand es 10:01 f\u00fcr Birkenau und so wurde munter durchgewechselt.\u00a0Nachdem man sich letztes Jahr an gleicher Stelle den Hemsbacherinnen knapp\u00a0geschlagen geben musste, wurden sie dieses Jahr vom TSV-Express nahezu \u00fcberrollt.\u00a0 Immer wieder konnten sch\u00f6ne Tempogegenst\u00f6\u00dfe unter dem Jubel der zahlreichen Fans im gegnerischen Tor untergebracht werden.<\/p>\n<p>Bereits vor dem letzten Spiel gegen die HG Oftersheim\/Schwetzingen, das mit 18:03 gewonnen wurde, standen die TSV-M\u00e4dels als Gruppensieger fest. Somit war der direkte Einzug in die Oberliga gesichert.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/w-jugend.tsv-birkenau.de\/wp-content\/upload\/aj_quali_fanblock.jpg\" alt=\"aj_quali_fanblock.jpg\" \/><\/p>\n<p>Unter dem Strich bleibt eine geschlossene Mannschaftsleistung, die letztendlich die erfolgreiche Qualifikation sicherte. Alle Spielerinnen bekamen viele Einsatzzeiten und jeder konnte so zu dem Erfolg beitragen. Einziger Wehrmutstropfen an diesem Tag war, dass sich Saskia Keller im Spiel gegen Hemsbach erneut einen Kreuzbandriss zugezogen hat. Ein gro\u00dfes Dankesch\u00f6n gilt den vielen Birkenauern Fans, die trotz der warmen Temperaturen in der Langenberghalle vertreten waren und f\u00fcr gute Stimmung sorgten.<\/p>\n<p>F\u00fcr den TSV waren im Einsatz:<br \/>\nVanessa Falter und Laura Essmann im Tor;<br \/>\nJana Bechtold, Lisa Schneiderheinze, Nicole Weidner, Saskia Keller, Monika Steffan, Patricia Scheidel, Sandja M\u00f6ckel, Sophia Weis, Melissa Hutzl, Mona G\u00f6ttmann, Jana G\u00f6lz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die weibliche A-Jugend des TSV Birkenau konnte sich am Sonntag, 04. Mai 2008,\u00a0 beim Qualifikationsturnier in Birkenau erneut f\u00fcr die Oberliga qualifizieren.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[24,1],"tags":[],"class_list":["post-823","post","type-post","status-publish","format-standard","hentry","category-a-jugend-2","category-allgemein"],"_links":{"self":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/comments?post=823"}],"version-history":[{"count":0,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/823\/revisions"}],"wp:attachment":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/media?parent=823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/categories?post=823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/tags?post=823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}