{"id":5244,"date":"2010-08-23T21:35:34","date_gmt":"2010-08-23T19:35:34","guid":{"rendered":"http:\/\/w-jugend.tsv-birkenau.de\/?p=5244"},"modified":"2010-08-29T20:30:34","modified_gmt":"2010-08-29T18:30:34","slug":"1b-damen-neue-und-alte-gesichter-starten-in-die-saison-20102011","status":"publish","type":"post","link":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/archives\/5244","title":{"rendered":"1b-Damen: Neue und alte Gesichter starten in die kommende Saison 2010\/2011"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5245\" title=\"web_trainer1b\" src=\"http:\/\/w-jugend.tsv-birkenau.de\/wp-content\/upload\/web_trainer1b.jpg\" alt=\"web_trainer1b\" width=\"400\" height=\"255\" srcset=\"https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/web_trainer1b.jpg 400w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/web_trainer1b-300x191.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p>Neue und alte Gesichter gibt es in dieser Runde zu sehen. Damit wachsen nat\u00fcrlich auch die Ziele und Erwartungen an die Mannschaft, den Trainer und die Verantwortlichen. <!--more--><\/p>\n<p>In der letzten Saison starteten die 1b-Damen hoch motiviert und als heimlicher Favorit in die Runde. Sie mussten aber schnell erkennen, dass der Ausfall von Stammspielerinnen durch nichts zu kompensieren ist. Das fr\u00fchzeitige Abschreiben jeglicher Aufstiegschancen war die schmerzliche Folge.<\/p>\n<p>Durch den Umbau dieses Teams blieb nat\u00fcrlich vieles nicht mehr, wie es war. Die Zug\u00e4nge aus der ersten, die das \u201eNeue&#8220; Team verst\u00e4rken, sowie die Integration der A-Jugendlichen trugen ihrerseits zur Reformation der ehemaligen Mannschaftsstruktur bei. Altgediente Spielerinnen mussten pl\u00f6tzlich auf neuen Positionen k\u00e4mpfen, Neuzug\u00e4nge ihre Pl\u00e4tze im Team finden und die jungen \u201eWilden&#8220; ihre Leitw\u00f6lfe ausmachen. Auch die Torh\u00fcter sahen sich durch berufliche Ver\u00e4nderungen pl\u00f6tzlich oft nur noch alleine im Training und mussten sich schnell der ver\u00e4nderten Situation stellen und behaupten. Das alles f\u00fchrte dazu, dass wir heuer mit einer zwar wieder ver\u00e4nderten, aber dennoch guten Mischung aus erfahrenen Spielerinnen und jungen Akteuren, die darauf brennen, sich in der Kreisliga zu zeigen, motiviert und engagiert in die neue Saison starten.<\/p>\n<p>Meine Aufgabe in der Mannschaft bestand darin, schnellstm\u00f6glich aus rund 16 Spielerinnen eine schlagkr\u00e4ftige Truppe zu formen. Au\u00dferdem musste ich kurzfristig ein Spielkonzept und Abwehrkonzept finden und verinnerlichen, dass es a) unseren Spielerinnen erm\u00f6glichte, trotz ihrer fehlenden K\u00f6rpergr\u00f6\u00dfe einen attraktiven Handball zu spielen, und b) versucht, die neuen Regeln dieser Saison f\u00fcr sich zu nutzen. Die Vorgabe der F\u00fchrungscrew, durch eine breit gef\u00e4cherte Arbeit eine Basis f\u00fcr attraktiven Damenhandballsport in allen Leistungsbereichen zu bieten, ist einer der grundlegendsten Bausteine. Nicht immer einfach waren hierbei, Anforderungen und W\u00fcnsche eines leistungsorientierten Trainers und die oft nur breitensportlichen Interessen einiger Beteiligten aufeinander abzustimmen. Bei den heutigen Anforderungen einer leistungsorientierten Mannschaft oder eines kpl. Spielbetriebes sto\u00dfen die Vereine ganz schnell an die Grenzen des finanziell Machbaren, deshalb ist es f\u00fcr uns besonders wichtig, durch ansprechenden und interessanten Handball ganz schnell neue und alte Fans wieder zu gewinnen, um weitere Werbepartner und Sponsoren auf uns aufmerksam zu machen.<\/p>\n<p>F\u00fcr das Engagement der ehrenamtlichen Arbeit aller Beteiligten m\u00f6chte ich mich hier bei allen ganz herzlich bedanken. Nur durch sie und viele Helfer ist es meinen M\u00e4dels und mir m\u00f6glich, jedes Jahr aufs Neue den f\u00fcr mich und viele andere \u201esch\u00f6nsten Sport der Welt&#8220; auszu\u00fcben.<\/p>\n<p>Vielen Dank!<\/p>\n<p>Gerold Leonhard<br \/>\nTrainer Damen 1b<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neue und alte Gesichter gibt es in dieser Runde zu sehen. Damit wachsen nat\u00fcrlich auch die Ziele und Erwartungen an die Mannschaft, den Trainer und die Verantwortlichen.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[45],"tags":[],"class_list":["post-5244","post","type-post","status-publish","format-standard","hentry","category-berichtdamen1b"],"_links":{"self":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/5244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/comments?post=5244"}],"version-history":[{"count":5,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/5244\/revisions"}],"predecessor-version":[{"id":5249,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/5244\/revisions\/5249"}],"wp:attachment":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/media?parent=5244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/categories?post=5244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/tags?post=5244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}