{"id":43645,"date":"2025-10-06T10:56:00","date_gmt":"2025-10-06T08:56:00","guid":{"rendered":"https:\/\/damenhandball.tsv-birkenau.de\/?p=43645"},"modified":"2025-10-06T10:56:00","modified_gmt":"2025-10-06T08:56:00","slug":"damen-1-mit-starker-defensive-und-glaenzender-torhueterin-tsv-birkenau-hsg-walzbachtal-3121-177","status":"publish","type":"post","link":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/archives\/43645","title":{"rendered":"Damen 1 mit starker Defensive und gl\u00e4nzender Torh\u00fcterin &#8211; TSV Birkenau \u2013 HSG Walzbachtal 31:21 (17:7)"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/TSV-1_HSG-Walzbachtal-05.10.25-Katrin.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/TSV-1_HSG-Walzbachtal-05.10.25-Katrin-1024x683.jpg\" alt=\"\" class=\"wp-image-43644\" srcset=\"https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/TSV-1_HSG-Walzbachtal-05.10.25-Katrin-1024x683.jpg 1024w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/TSV-1_HSG-Walzbachtal-05.10.25-Katrin-300x200.jpg 300w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/TSV-1_HSG-Walzbachtal-05.10.25-Katrin-768x512.jpg 768w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/TSV-1_HSG-Walzbachtal-05.10.25-Katrin-930x620.jpg 930w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/TSV-1_HSG-Walzbachtal-05.10.25-Katrin.jpg 1199w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p>Mit einer beeindruckenden Abwehrleistung und einer \u00fcberragenden Johanna Meyer im Tor feierten die Damen des TSV Birkenau in der Langenberghalle einen deutlichen 31:21-Erfolg \u00fcber die bislang ungeschlagene HSG Walzbachtal. Damit setzte der TSV ein klares Ausrufezeichen in der noch jungen Oberliga-Saison.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Die G\u00e4ste aus Walzbachtal reisten mit drei Siegen im R\u00fccken als Topfavorit an, doch Birkenau lie\u00df von Beginn an keinen Zweifel daran, dass man an diesem Tag ein Zeichen setzen wollte. Cheftrainerin Katharina Leinert sah eine konzentrierte Anfangsphase ihres Teams, das in den ersten neun Minuten lediglich zwei Gegentreffer \u2013 beide per Siebenmeter \u2013 zulie\u00df. Aus dem Spiel heraus blieb Walzbachtal chancenlos oder scheiterte an der b\u00e4renstarken Johanna Meyer, die mit zahlreichen Paraden den Grundstein f\u00fcr eine fr\u00fche F\u00fchrung legte.<\/p>\n\n\n\n<p>Mit einem furiosen 8:0-Lauf zog der TSV auf 14:3 davon. Erst in der 25. Minute gelang Walzbachtal der vierte Treffer, w\u00e4hrend Linn Gutsche kurz vor der Pause sehenswert aus dem R\u00fcckraum zum 17:7-Halbzeitstand traf.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/TSV-1_HSG-Walzbachtal-05.10.25-Anna.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/TSV-1_HSG-Walzbachtal-05.10.25-Anna.jpg\" alt=\"\" class=\"wp-image-43642\" srcset=\"https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/TSV-1_HSG-Walzbachtal-05.10.25-Anna.jpg 800w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/TSV-1_HSG-Walzbachtal-05.10.25-Anna-300x300.jpg 300w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/TSV-1_HSG-Walzbachtal-05.10.25-Anna-150x150.jpg 150w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/TSV-1_HSG-Walzbachtal-05.10.25-Anna-768x768.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n\n\n\n<p>Nach dem Seitenwechsel brauchte Birkenau zwar f\u00fcnf Minuten, ehe Josi Leinert das 18:9 erzielte, doch der Spielfluss blieb aufseiten der Gastgeberinnen. Walzbachtal konnte den R\u00fcckstand nicht mehr entscheidend verk\u00fcrzen, zu stabil stand die TSV-Abwehr, zu konzentriert agierte das Team im R\u00fcckzugsverhalten.<\/p>\n\n\n\n<p>Besonders treffsicher zeigte sich Danijela Rajic, die zun\u00e4chst f\u00fcnf Siebenmeter sicher verwandelte und sp\u00e4ter auch aus dem Feld erfolgreich war \u2013 insgesamt acht Treffer standen f\u00fcr sie am Ende zu Buche. Weder die Manndeckung gegen Linn Gutsche und Josi Leinert noch eine offensive Deckungsvariante brachten die G\u00e4ste entscheidend n\u00e4her heran. Im Gegenteil: In den letzten zehn Minuten baute der TSV seinen Vorsprung wieder kontinuierlich aus.<\/p>\n\n\n\n<p>Sinnbildlich f\u00fcr die geschlossene Mannschaftsleistung war der letzte Treffer des Abends \u2013 erneut durch Danijela Rajic per Siebenmeter \u2013 zum 31:21-Endstand.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/TSV-1_HSG-Walzbachtal-05.10.25-Anne.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/TSV-1_HSG-Walzbachtal-05.10.25-Anne-1024x683.jpg\" alt=\"\" class=\"wp-image-43643\" srcset=\"https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/TSV-1_HSG-Walzbachtal-05.10.25-Anne-1024x683.jpg 1024w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/TSV-1_HSG-Walzbachtal-05.10.25-Anne-300x200.jpg 300w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/TSV-1_HSG-Walzbachtal-05.10.25-Anne-768x512.jpg 768w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/TSV-1_HSG-Walzbachtal-05.10.25-Anne-930x620.jpg 930w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/TSV-1_HSG-Walzbachtal-05.10.25-Anne.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p>Cheftrainerin Leinert lobte die Mannschaft, richtete aber den Blick gleich wieder nach vorne: \u201eVor allem die ersten 30 Minuten war das beste Spiel, das ich von meiner Mannschaft seit langem gesehen habe. Hier lief fast alles zusammen. Die M\u00e4dels haben sich diesen Sieg extrem verdient. Sie haben unser Konzept \u00fcber weite Strecken vorbildlich umgesetzt und sich an Absprachen gehalten. Das macht Spa\u00df zu sehen. Nichtsdestotrotz gibt es auch f\u00fcr diese Leistung \u201enur\u201c 2 Punkte. Die Saison ist noch jung und n\u00e4chste Woche kommt schon der n\u00e4chste schwere Gegner. F\u00fcr heute d\u00fcrfen und sollen wir uns \u00fcber diesen Sieg freuen. Ab Montag wird wieder gearbeitet.\u201c, so Leinert nach der Begegnung.<\/p>\n\n\n\n<p>Dieser deutliche Erfolg gegen einen ambitionierten Gegner gibt Selbstvertrauen f\u00fcr die bevorstehende Aufgabe. Am 11.10. trifft man auf SV Leonberg\/Eltingen zum dritten Heimspiel in Folge. F\u00fcr diese Partie hofft man auf zahlreiche Zuschauer, die die Mannschaft lautstark unterst\u00fctzt. Anwurf ist 19:30h.<\/p>\n\n\n\n<p>TSV Birkenau: Johanna Meyer, Katharina Bussek (im Tor), Danijela Rajic (8), Josi Leinert (6), Jacqueline Tines (5), Linn Gutsche (4), Alexa Becker (3), Katrin Haas (3), Marie Harbarth (1), Mathilda Pfisterer (1), Beeke Falter, Marina Hassel, Anne Havemann, Anna Knapp, Lilly Knogler<\/p>\n\n\n\n<p>(Bilder: Armin Etzel)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit einer beeindruckenden Abwehrleistung und einer \u00fcberragenden Johanna Meyer im Tor feierten die Damen des TSV Birkenau in der Langenberghalle einen deutlichen 31:21-Erfolg \u00fcber die bislang ungeschlagene HSG Walzbachtal. Damit setzte der TSV ein klares Ausrufezeichen in der noch jungen Oberliga-Saison.<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[44],"tags":[],"class_list":["post-43645","post","type-post","status-publish","format-standard","hentry","category-berichtdamen1"],"_links":{"self":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/43645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/comments?post=43645"}],"version-history":[{"count":1,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/43645\/revisions"}],"predecessor-version":[{"id":43646,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/43645\/revisions\/43646"}],"wp:attachment":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/media?parent=43645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/categories?post=43645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/tags?post=43645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}