{"id":42689,"date":"2024-01-29T19:39:19","date_gmt":"2024-01-29T18:39:19","guid":{"rendered":"https:\/\/w-jugend.tsv-birkenau.de\/?p=42689"},"modified":"2024-01-30T07:27:10","modified_gmt":"2024-01-30T06:27:10","slug":"erste-niederlage-fuer-unsere-damen-sg-heddesheim-tsv-birkenau-2320-107","status":"publish","type":"post","link":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/archives\/42689","title":{"rendered":"Erste Niederlage f\u00fcr unsere Damen \u2013 SG Heddesheim \u2013 TSV Birkenau 23:20 (10:7)"},"content":{"rendered":"\n<p>Erschreckend schwach pr\u00e4sentierte sich der Tabellenf\u00fchrer der Badenliga beim Derby in Heddesheim. Aufgrund einer katastrophalen Chancenverwertung verlor der TSV verdient den Start in die R\u00fcckrunde.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Gleich zwei erfreuliche Meldungen gab es auf Seiten des TSV zu vermelden. Mit Katharina Leinert konnten wir eine erfahrene Torwarttrainerin gewinnen, die bis 2019 selbst das Trikot des TSV trug. Ebenfalls keine Unbekannte, Angelina Schreyer, die den Kader verst\u00e4rkt. Mehr positive Meldungen gab es leider nicht zu berichten.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/w-jugend.tsv-birkenau.de\/wp-content\/upload\/SGH-vs-TSV-29.01.24-Linn.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"http:\/\/w-jugend.tsv-birkenau.de\/wp-content\/upload\/SGH-vs-TSV-29.01.24-Linn-1024x683.jpg\" alt=\"\" class=\"wp-image-42688\" srcset=\"https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/SGH-vs-TSV-29.01.24-Linn-1024x683.jpg 1024w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/SGH-vs-TSV-29.01.24-Linn-300x200.jpg 300w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/SGH-vs-TSV-29.01.24-Linn-768x512.jpg 768w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/SGH-vs-TSV-29.01.24-Linn.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p>Aufgrund der Tabellensituation fuhr der TSV als Favorit zum Nachbarschaftsduell nach Heddesheim. Eine Rolle, der man im kompletten Spiel in keinster Weise gerecht werden konnte. Bis zum 7:7 (18.) funktionierte nicht viel, aber immerhin war man noch im Spiel. In den verbleidenden 12.Minuten (!) der erschreckend schwachen ersten H\u00e4lfte fiel kein Treffer mehr zu Gunsten des TSV. Mit einem Drei-Tore-R\u00fcckstand ging es in die Pause (7:10).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/w-jugend.tsv-birkenau.de\/wp-content\/upload\/SGH-vs-TSV-29.01.24-Lenya.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"http:\/\/w-jugend.tsv-birkenau.de\/wp-content\/upload\/SGH-vs-TSV-29.01.24-Lenya-1024x683.jpg\" alt=\"\" class=\"wp-image-42687\" srcset=\"https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/SGH-vs-TSV-29.01.24-Lenya-1024x683.jpg 1024w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/SGH-vs-TSV-29.01.24-Lenya-300x200.jpg 300w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/SGH-vs-TSV-29.01.24-Lenya-768x512.jpg 768w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/SGH-vs-TSV-29.01.24-Lenya.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p>Nach dem Seitenwechsel k\u00e4mpften sich die M\u00e4dels allm\u00e4hlig wieder heran und kamen f\u00fcnf Minuten vor Abpfiff sogar noch zum Ausgleich (20:20). Aber die Einladung der Gastgeber, dieses Spiel g\u00e4nzlich zu drehen, nahmen sie nicht an. Wie schon im ganzen Match f\u00fchrten einfache Fehler zu Ballverlusten, die der Gegner zu Gegentoren nutzen konnte. Am Ende stand eine bittere und v\u00f6llig unn\u00f6tige Derby-Niederlage (20:23).&nbsp;<\/p>\n\n\n\n<p>Nun gilt es das Spiel schnell wieder aus den K\u00f6pfen zu bekommen und an die hervorragende Leistung aus der Hinrunde anzukn\u00fcpfen. Am 04.02. empf\u00e4ngt man Schlusslicht HSG St.Leon\/Reilingen 2 in eigener Halle. Anwurf ist 15h.<\/p>\n\n\n\n<p>F\u00fcr den TSV spielten: Johanna Meyer, Katharina Bussek (im Tor), Monika Reiter (3), Katrin Haas, Danijela Rajic, Anna Baumann, Lejla Crnisanin (3), Marie Harbarth (4\/2), Lenya Hanke (1), Angelina Schreyer, Alexa Becker, Linn Gutsche (6), Ophelia Schall, Jacqueline Mader (3\/1)<\/p>\n\n\n\n<p>(Bilder: Armin Etzel)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erschreckend schwach pr\u00e4sentierte sich der Tabellenf\u00fchrer der Badenliga beim Derby in Heddesheim. Aufgrund einer katastrophalen Chancenverwertung verlor der TSV verdient den Start in die R\u00fcckrunde.<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[44],"tags":[],"class_list":["post-42689","post","type-post","status-publish","format-standard","hentry","category-berichtdamen1"],"_links":{"self":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/42689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/comments?post=42689"}],"version-history":[{"count":4,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/42689\/revisions"}],"predecessor-version":[{"id":42695,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/42689\/revisions\/42695"}],"wp:attachment":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/media?parent=42689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/categories?post=42689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/tags?post=42689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}