{"id":42397,"date":"2023-10-09T11:52:57","date_gmt":"2023-10-09T09:52:57","guid":{"rendered":"http:\/\/w-jugend.tsv-birkenau.de\/?p=42397"},"modified":"2023-10-09T11:52:59","modified_gmt":"2023-10-09T09:52:59","slug":"weibliche-d-jugend-verteidigt-souveraen-die-tabellenspitze","status":"publish","type":"post","link":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/archives\/42397","title":{"rendered":"Weibliche D-Jugend verteidigt souver\u00e4n die Tabellenspitze"},"content":{"rendered":"\n<p>Am Dienstag trat die weibliche D-Jugend zu ihrem dritten Spieltag und zweiten Heimspieltag an. Im Spiel gegen HSG Dielheim\/Malschenberg kristallisierte sich schnell heraus, dass die M\u00e4dels die zwei Punkte auf jeden Fall zuhause behalten wollen.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Vor allem das schnelle R\u00fcckraumspiel von Jette Schmitt, Annika Martin und Emmy Zahn \u00fcberzeugte und geschickte Kreisanspiele verwertete Juliana K\u00fchnel eiskalt. So konnten die M\u00e4dels mit einem Spielstand von 13:4 beruhigt in die Halbzeitpause gehen. Mit einer klasse Abwehr- und Torh\u00fcterleistung als Basis, dominierten die Spielerinnen der wD die gesamte Spielzeit \u00fcber.<\/p>\n\n\n\n<p>In der zweiten Halbzeit bauten die TSV M\u00e4dels ihren Vorsprung weiter aus. Was die Trainerinnen sehr freute, war, dass in der gesamten Spielzeit auch die jungen sowie unerfahrenen Spielerinnen zum Zug kamen und diese ihre Sache richtig gut machten. Das Spiel endete nach Addition der Torsch\u00fctzen mit 32 : 12 f\u00fcr den TSV. Somit bleibt die wD-Jugend mit 8:0 Punkten an der Tabellenspitze. Die Trainerinnen hoffen, dass dieser Rang auch im n\u00e4chsten Spiel gegen SG Nu\u00dfloch gehalten wird. Sie sind stolz auf die Leistung der M\u00e4dels.<\/p>\n\n\n\n<p><strong>TSV Birkenau: <\/strong>Mila Martin-Keskin, Mathilda Rodriguez Thieme, Josefine Thirolf. Maya Rybakov ( 1), Lina Pfl\u00e4sterer-Treceno,  Louisa Klein, Annika Martin ( 5\/1), Jette Schmitt (12), Juliana K\u00fchnel ( 3), Emmy Zahn ( 9), Leyan Seyfeddin ( 1), Diana Krahn (1), Maja Schr\u00f6der<\/p>\n\n\n\n<p>(Bericht: S. Thun-Falter)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am Dienstag trat die weibliche D-Jugend zu ihrem dritten Spieltag und zweiten Heimspieltag an. Im Spiel gegen HSG Dielheim\/Malschenberg kristallisierte sich schnell heraus, dass die M\u00e4dels die zwei Punkte auf jeden Fall zuhause behalten wollen.<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[27],"tags":[],"class_list":["post-42397","post","type-post","status-publish","format-standard","hentry","category-d-jugend-2"],"_links":{"self":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/42397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/comments?post=42397"}],"version-history":[{"count":1,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/42397\/revisions"}],"predecessor-version":[{"id":42398,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/42397\/revisions\/42398"}],"wp:attachment":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/media?parent=42397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/categories?post=42397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/tags?post=42397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}