{"id":42042,"date":"2023-01-16T16:41:17","date_gmt":"2023-01-16T15:41:17","guid":{"rendered":"http:\/\/w-jugend.tsv-birkenau.de\/?p=42042"},"modified":"2023-01-16T16:41:19","modified_gmt":"2023-01-16T15:41:19","slug":"damen-1b-starten-mit-einem-sieg-in-das-jahr-2023-tsv-birkenau-2-sg-walldorf-astoria-3026-1414","status":"publish","type":"post","link":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/archives\/42042","title":{"rendered":"Damen 1b starten mit einem Sieg in das Jahr 2023 \u2013 TSV Birkenau 2 &#8211; SG Walldorf Astoria 30:26 (14:14)"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/w-jugend.tsv-birkenau.de\/wp-content\/upload\/DSC_0094-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" src=\"http:\/\/w-jugend.tsv-birkenau.de\/wp-content\/upload\/DSC_0094-1024x681.jpg\" alt=\"\" class=\"wp-image-42040\" srcset=\"https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/DSC_0094-1024x681.jpg 1024w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/DSC_0094-300x199.jpg 300w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/DSC_0094-768x511.jpg 768w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/DSC_0094-1536x1021.jpg 1536w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/DSC_0094-2048x1362.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p>Zum R\u00fcckrundenauftakt fanden die Sch\u00fctzlinge von Moritz Dornseiff erst sp\u00e4t ins Spiel, fuhren am Ende dann doch verdient den elften Sieg in Folge ein. Nele Heckmann, die nach ihrem Auslandsaufenthalt wieder zur\u00fcck ist, steuerte bei ihrem Debut zwei Treffer bei.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>In der Anfangsphase der ersten Halbzeit zeigten die G\u00e4ste wenig Respekt vor dem Tabellenf\u00fchrer. Bis zum 7:7 begegneten sich beide Mannschaften zun\u00e4chst auf Augenh\u00f6he. Doch ab der 12. Spielminuten leistete sich der TSV einige Fehler, die die G\u00e4ste zu einer 4-Tore-F\u00fchrung nutzten (8:12, 19. Minute). Erst sechs Minuten vor dem Seitenwechsel fanden die M\u00e4dels vom TSV zur\u00fcck ins Spiel und glichen bis zum Pausenpfiff aus. Beim Spielstand von 14:14 wurden die Seiten gewechselt.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/w-jugend.tsv-birkenau.de\/wp-content\/upload\/DSC_0097-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" src=\"http:\/\/w-jugend.tsv-birkenau.de\/wp-content\/upload\/DSC_0097-1024x681.jpg\" alt=\"\" class=\"wp-image-42039\" srcset=\"https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/DSC_0097-1024x681.jpg 1024w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/DSC_0097-300x199.jpg 300w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/DSC_0097-768x511.jpg 768w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/DSC_0097-1536x1021.jpg 1536w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/DSC_0097-2048x1362.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p>Moritz Dornseiff schien in der Halbzeitansprache die richtigen Worte gefunden zu haben. Die TSV\u2019lerinnen kamen engagierter aus der Kabine und legten bereits fr\u00fch den Grundstein f\u00fcr den n\u00e4chsten Sieg. W\u00e4hrend die Abwehr nun beherzter agierte brauchten Lenya Hanke, Mona G\u00f6ttmann und Alex Becker keine zehn Minuten, um auf 19:15 zu stellen. Walldorf Astoria hatte in dieser Phase der Partie mehr nichts entgegenzusetzen. &nbsp;Tor um Tor baute der TSV die F\u00fchrung weiter aus (28:20, 54 Minute). F\u00fcr die G\u00e4ste reichte es lediglich noch zu einer Ergebniskosmetik. Bei Abpfiff stand ein 30:26 Heimsieg f\u00fcr den TSV auf der Anzeigentafel.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/w-jugend.tsv-birkenau.de\/wp-content\/upload\/DSC_0088-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" src=\"http:\/\/w-jugend.tsv-birkenau.de\/wp-content\/upload\/DSC_0088-1024x681.jpg\" alt=\"\" class=\"wp-image-42041\" srcset=\"https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/DSC_0088-1024x681.jpg 1024w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/DSC_0088-300x200.jpg 300w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/DSC_0088-768x511.jpg 768w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/DSC_0088-1536x1022.jpg 1536w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/DSC_0088-2048x1362.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p>Gerade in der zweiten Halbzeit bot der Spitzenreiter der Verbandsliga eine gewohnt gute und geschlossene Mannschaftsleistung. Die Defensive, die in Halbzeit eins noch einigen Problemen hatte, stand deutlich stabiler. Lenya Hanke steuerte sage und schreibe 13 Treffer in diesem Spiel bei und bewies damit nicht zum ersten Mal ihre Treffsicherheit. Mo Dornseiff hat nun bis zum 05. Februar Zeit die Mannschaft auf das n\u00e4chste Heimspiel gegen die TG Neureut einzustimmen.<\/p>\n\n\n\n<p>Es spielten: Katharina Bussek, Jessica Wagner (im Tor), Monika Reiter (4), Nele Heckmann (2), Kristina Falter, Mona G\u00f6ttmann (4), Sarah Bussek (1), Lenja M\u00fcller (2), Lenya Hanke (13\/2), Alisa Murowatz (1), Marina Hassel, Alexa Becker (3)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zum R\u00fcckrundenauftakt fanden die Sch\u00fctzlinge von Moritz Dornseiff erst sp\u00e4t ins Spiel, fuhren am Ende dann doch verdient den elften Sieg in Folge ein. Nele Heckmann, die nach ihrem Auslandsaufenthalt wieder zur\u00fcck ist, steuerte bei ihrem Debut zwei Treffer bei.<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[45],"tags":[],"class_list":["post-42042","post","type-post","status-publish","format-standard","hentry","category-berichtdamen1b"],"_links":{"self":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/42042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/comments?post=42042"}],"version-history":[{"count":1,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/42042\/revisions"}],"predecessor-version":[{"id":42043,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/42042\/revisions\/42043"}],"wp:attachment":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/media?parent=42042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/categories?post=42042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/tags?post=42042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}