{"id":41177,"date":"2021-10-03T14:56:04","date_gmt":"2021-10-03T12:56:04","guid":{"rendered":"http:\/\/w-jugend.tsv-birkenau.de\/?p=41177"},"modified":"2021-10-03T14:56:06","modified_gmt":"2021-10-03T12:56:06","slug":"1b-damen-starten-mit-heimsieg-in-saison","status":"publish","type":"post","link":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/archives\/41177","title":{"rendered":"1b-Damen starten mit Heimsieg in Saison"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Die Birkenauer 1b-Damen starteten mit einem 20:14 (11:03)-Heimsieg in die neue Verbandsliga-Saison. In der zweigeteilten Liga in Gruppe A leisteten sich beide Mannschaften zun\u00e4chst viele Fehler. Erst in der 7. Spielminute konnte so das erste Tor auf TSV-Seite verbucht werden. <\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">In der Folge gelangen \u00fcber eine konzentriert arbeitende Abwehr Ballgewinne, aus denen Kontertore resultierten. Da Torfrau Birgit Schura einen guten Tag erwischte und Ilvesheim zudem einige B\u00e4lle \u00fcber das Tor setzte, baute die junge TSV-Truppe um ihren neuen Trainer Moritz Dornseiff ihren Vorsprung bis zum 8:0 (17.) weiter aus. Jetzt erst konnten die G\u00e4ste ihren ersten eigenen Treffer verbuchen. Alle eingesetzten A-Jugendlichen gaben ihren Einstand in den Aktiven und zeigten sich unbeeindruckt von den \u00e4lteren Gegenspielerinnen. Gemeinsam mit den etatm\u00e4\u00dfigen 1b-Spielerinnen und zwei 1- Damenspielerinnen stellte sich inzwischen ein Spielfluss ein, sodass mit dem deutlichen 11:03-Stand die Seiten gewechselt wurde. Da die Defensive nach Wiederanpfiff nachl\u00e4ssiger wurde und auch in der Offensive zun\u00e4chst die Ideen und guten Entscheidungen fehlten, gelang Ilvesheim nun mehr eigene Treffer. So stand es nach 38 Spielminuten 14:09 f\u00fcr die gastgebenden TSV-Damen. Im weiteren Verlauf des Spiels besannen sich die Birkenauerinnen wieder mehr auf ihre Grundtugenden und feierten so am Ende mit dem 20:14-Heimsieg den ersten doppelten Punktgewinn der neuen Saison. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TSV: Schura und Sch\u00fctz im Tor; Martin 4, B\u00fcrner 5\/1,\nPfenning, Zehrbach, M\u00fcller 4, Hanke 6, Drost 1, Weber<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Birkenauer 1b-Damen starteten mit einem 20:14 (11:03)-Heimsieg in die neue Verbandsliga-Saison. In der zweigeteilten Liga in Gruppe A leisteten sich beide Mannschaften zun\u00e4chst viele Fehler. Erst in der 7. Spielminute konnte so das erste Tor auf TSV-Seite verbucht werden.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[45],"tags":[],"class_list":["post-41177","post","type-post","status-publish","format-standard","hentry","category-berichtdamen1b"],"_links":{"self":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/41177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/comments?post=41177"}],"version-history":[{"count":1,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/41177\/revisions"}],"predecessor-version":[{"id":41178,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/41177\/revisions\/41178"}],"wp:attachment":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/media?parent=41177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/categories?post=41177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/tags?post=41177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}