{"id":41136,"date":"2021-09-03T11:39:53","date_gmt":"2021-09-03T09:39:53","guid":{"rendered":"http:\/\/w-jugend.tsv-birkenau.de\/?p=41136"},"modified":"2021-09-03T11:39:54","modified_gmt":"2021-09-03T09:39:54","slug":"vom-odenwald-nach-westafrika","status":"publish","type":"post","link":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/archives\/41136","title":{"rendered":"Vom Odenwald nach Westafrika:"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Nele goes Benin! <\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/w-jugend.tsv-birkenau.de\/wp-content\/upload\/Nele@Damen1-683x1024.jpg\" alt=\"\" class=\"wp-image-41137\" width=\"227\" height=\"339\" srcset=\"https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/Nele@Damen1-683x1024.jpg 683w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/Nele@Damen1-200x300.jpg 200w\" sizes=\"auto, (max-width: 227px) 100vw, 227px\" \/><figcaption>Nele im TSV-Dress<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Nach wochenlangem Warten und intensiver und aufw\u00e4ndiger Vorbereitung steht es nun fest: <br>Die langj\u00e4hrige TSV Nachwuchsspielerin Nele Heckmann (bisher A-Jugend und Damen1) wird ab Oktober im Rahmen der \u201eweltw\u00e4rts\u201c-Organisation der Bundesregierung zu einem neun-monatigen Einsatz nach Benin in Westafrika gehen, um dort am Complexe Scolaire Saint Georges in Cotonou als Sprachlehrerin f\u00fcr Kinder ab sechs Jahre zu arbeiten. Tr\u00e4ger der Ma\u00dfnahme ist \u201eExperiment e.V.\u201c, ein an \u201eweltw\u00e4rts\u201c angegliederter Tr\u00e4ger von internationalen Eins\u00e4tzen f\u00fcr Freiwillige.  F\u00fcr ihren geliebten Handballsport hei\u00dft es erst einmal Pause. \u201eSchon lange steht f\u00fcr mich fest, dass ich f\u00fcr l\u00e4ngere Zeit ins Ausland gehen m\u00f6chte, um mich dort in einem entwicklungspolitischen Projekt zu engagieren. <br>Dabei geht es mir vor allen Dingen darum, von und mit anderen Menschen zu lernen und mich auch langfristig f\u00fcr eine globale nachhaltige Entwicklung einzusetzen. In unserer Welt gibt es so viele ungleiche Lebensbedingungen und ich erhoffe mir durch meinen Freiwilligendienst wenigstens einen kleinen Teil Richtung Gerechtigkeit beitragen zu k\u00f6nnen und daran pers\u00f6nlich zu wachsen. Des Weiteren bin ich davon \u00fcberzeugt, dass solch eine Erfahrung mir sehr viel mitgibt, was mir hilft meine eigenen Werte zu \u00fcberdenken und zu ordnen.\u201c so Nele zu ihrem Einsatz in Benin. \u201eDer Handball und meine Mannschaften in Birkenau fehlen mir heute schon sehr \u2013 durch Corona, Abitur und die Vorbereitungen f\u00fcr den Aufenthalt in Benin war mir eine Teilnahme am Training in Birkenau in letzter Zeit leider nicht m\u00f6glich.\u201c<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"155\" src=\"http:\/\/w-jugend.tsv-birkenau.de\/wp-content\/upload\/Weltw\u00e4rtsLOGOS-1024x155.jpg\" alt=\"\" class=\"wp-image-41139\" srcset=\"https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/Weltw\u00e4rtsLOGOS-1024x155.jpg 1024w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/Weltw\u00e4rtsLOGOS-300x45.jpg 300w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/Weltw\u00e4rtsLOGOS-768x116.jpg 768w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/Weltw\u00e4rtsLOGOS.jpg 1093w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eW\u00e4hrend meiner Abwesenheit muss halt mein\nBruder Jonas die TSV-Fahne f\u00fcr die Familie hochhalten\u201c, so Nele lachend.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Ihr mehr \u00fcber Nele und Ihren Einsatz erfahren wollt, dann schaut auf ihrer Homepage <a href=\"http:\/\/nelegoesabroad.de\/\"><strong>Nele goes abroad<\/strong><\/a><strong> <\/strong> vorbei und tragt Euch in ihr G\u00e4stebuch ein. Dann werdet Ihr immer mit den neuesten Infos versorgt. Hier seht ihr auch, wie Ihr Nele unterst\u00fctzen k\u00f6nnt, wenn Ihr dies m\u00f6chtet.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/w-jugend.tsv-birkenau.de\/wp-content\/upload\/Nele_2-768x1024.jpg\" alt=\"\" class=\"wp-image-41146\" width=\"184\" height=\"245\" srcset=\"https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/Nele_2-768x1024.jpg 768w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/Nele_2-225x300.jpg 225w\" sizes=\"auto, (max-width: 184px) 100vw, 184px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir w\u00fcnschen Nele alles Gute f\u00fcr Ihren Einsatz in Afrika und freuen uns auf Ihre R\u00fcckkehr zum TSV Team.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nele goes Benin! Nach wochenlangem Warten und intensiver und aufw\u00e4ndiger Vorbereitung steht es nun fest: Die langj\u00e4hrige TSV Nachwuchsspielerin Nele Heckmann (bisher A-Jugend und Damen1) wird ab Oktober im Rahmen der \u201eweltw\u00e4rts\u201c-Organisation der Bundesregierung zu einem neun-monatigen Einsatz nach Benin in Westafrika gehen, um dort am Complexe Scolaire Saint Georges in Cotonou als Sprachlehrerin f\u00fcr&hellip;&nbsp;<a href=\"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/archives\/41136\" rel=\"bookmark\">Weiterlesen &raquo;<span class=\"screen-reader-text\">Vom Odenwald nach Westafrika:<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-41136","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/41136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/comments?post=41136"}],"version-history":[{"count":8,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/41136\/revisions"}],"predecessor-version":[{"id":41149,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/41136\/revisions\/41149"}],"wp:attachment":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/media?parent=41136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/categories?post=41136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/tags?post=41136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}