{"id":41131,"date":"2021-08-04T09:38:17","date_gmt":"2021-08-04T07:38:17","guid":{"rendered":"http:\/\/w-jugend.tsv-birkenau.de\/?p=41131"},"modified":"2022-08-12T16:55:03","modified_gmt":"2022-08-12T14:55:03","slug":"damen-1b-mit-neuem-trainer","status":"publish","type":"post","link":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/archives\/41131","title":{"rendered":"Damen 1B mit neuem Trainer"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/w-jugend.tsv-birkenau.de\/wp-content\/upload\/image-4-768x1024.png\" alt=\"\" class=\"wp-image-41132\" width=\"390\" height=\"519\" srcset=\"https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/image-4-768x1024.png 768w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/image-4-225x300.png 225w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/image-4.png 1536w\" sizes=\"auto, (max-width: 390px) 100vw, 390px\" \/><figcaption>Neuer Trainer der Damen 1B: Moritz Dornseiff<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Die Birkenauer 1b-Damen, die in die Saison 21\/22 in der in zwei regionale Gruppen aufgeteilten Verbandsliga starten werden, haben einen neuen Trainer. Mit dem Mit-Zwanziger Moritz Dornseiff, der selbst aktiver Spieler ist und bereits jahrelange Erfahrungen im Traineramt  aufweist, ist ein Nachfolger f\u00fcr die ehemaligen Verantwortlichen Bernd Gei\u00df und Bernhard Stichling gefunden. Dornseiff war bei der HG Saase bereits mit dem neu verpflichteten Birkenauer 1.Damenmannschaftstrainer Carsten Sender gemeinsam Mannschaftsverantwortlicher. Mit Moritz Dornseiff soll die wichtige Schnittstellenarbeit mit ebengenanntem Carsten Sender wie auch A-Jugend-Trainer Waldemar Rack gelingen. Die Birkenauer 1b-Damen starten am Wochenende 02.\/03. Oktober in die Saison und sind froh, inzwischen wieder gemeinsam rund um den Handball aktiv sein zu k\u00f6nnen.<br><br>Bericht: Linda Sch\u00e4fer<br>Foto: M. Dornseiff<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Birkenauer 1b-Damen, die in die Saison 21\/22 in der in zwei regionale Gruppen aufgeteilten Verbandsliga starten werden, haben einen neuen Trainer. Mit dem Mit-Zwanziger Moritz Dornseiff, der selbst aktiver Spieler ist und bereits jahrelange Erfahrungen im Traineramt aufweist, ist ein Nachfolger f\u00fcr die ehemaligen Verantwortlichen Bernd Gei\u00df und Bernhard Stichling gefunden. Dornseiff war bei&hellip;&nbsp;<a href=\"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/archives\/41131\" rel=\"bookmark\">Weiterlesen &raquo;<span class=\"screen-reader-text\">Damen 1B mit neuem Trainer<\/span><\/a><\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[45,1],"tags":[],"class_list":["post-41131","post","type-post","status-publish","format-standard","hentry","category-berichtdamen1b","category-allgemein"],"_links":{"self":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/41131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/comments?post=41131"}],"version-history":[{"count":2,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/41131\/revisions"}],"predecessor-version":[{"id":41134,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/41131\/revisions\/41134"}],"wp:attachment":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/media?parent=41131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/categories?post=41131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/tags?post=41131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}