{"id":16278,"date":"2013-04-02T16:56:17","date_gmt":"2013-04-02T14:56:17","guid":{"rendered":"http:\/\/w-jugend.tsv-birkenau.de\/?p=16278"},"modified":"2013-04-02T16:57:18","modified_gmt":"2013-04-02T14:57:18","slug":"das-spiel-entfallt-wegen-schiedsrichtermangel","status":"publish","type":"post","link":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/archives\/16278","title":{"rendered":"&#8222;Das Spiel am Wochenende entf\u00e4llt aufgrund von Schiedsrichtermangel im Verband!&#8220;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-16279\" alt=\"Schiedsrichtermangel\" src=\"http:\/\/w-jugend.tsv-birkenau.de\/wp-content\/upload\/web_HBW_AZ_Karten_A6_QF_4c_02.jpg\" width=\"420\" height=\"298\" srcset=\"https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/web_HBW_AZ_Karten_A6_QF_4c_02.jpg 420w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/web_HBW_AZ_Karten_A6_QF_4c_02-300x212.jpg 300w\" sizes=\"auto, (max-width: 420px) 100vw, 420px\" \/><\/p>\n<p>Stellen Sie sich vor, es ist Sonntagmittag, Sie freuen sich darauf, in der Langenberghalle ein spannendes Handballspiel mitzuerleben und dann das: aufgrund des akuten Schiedsrichtermangels muss das Spiel ausfallen!<!--more--><\/p>\n<p>Auch wenn diese Vorstellung sehr hart klingt, verdeutlicht sie die aktuelle Lage des Badischen-Handball-Verbandes, was die Situation des Schiedsrichtermangels betrifft. Dass trotz des enormen Mangels ein geregelter Spielbetrieb stattfinden kann, verlangt von den einsetzbaren Schiedsrichtergespannen, dass diese mehrere Spiele an einem Wochenende oder auch an einem Tag pfeifen.<\/p>\n<p>Um diesem Mangel entgegen zu wirken hat TSV-Abteilungsleiter Michael Weber gemeinsam mit dem BHV-Schiedsrichter Johannes Kern ein Konzept angesto\u00dfen, wie im Verein Interessierte \/ Engagierte motiviert werden, k\u00f6nnen als Schiedsrichter\/in t\u00e4tig zu werden. Auch wenn der TSV Birkenau aktuell erstmals das geforderte Schiedsrichter-Soll von 7 Schiedsrichtern erf\u00fcllt, muss auf die n\u00e4chste Saison geschaut werden, dort ben\u00f6tigt der TSV aufgrund einer Regel\u00e4nderung des Badischen-Handball-Verbandes 18 Schiedsrichter!<\/p>\n<p>Wird die Zahl der Schiedsrichter von einem Verein nicht erf\u00fcllt, fallen im ersten Jahr Geldstrafen und im Wiederholungsfalle sogar Punktabz\u00fcge bei der h\u00f6chstklassigen Aktivenmannschaft im Bereich der BHV-Ligen an.<\/p>\n<p>Das gerade erarbeitete Projekt sieht z.B. vor, die vereinseigenen Schiedsrichter aktiv zu unterst\u00fctzen und mit ihnen auch regelm\u00e4\u00dfige Treffen zum Weiterbilden stattfinden zu lassen. Schiedsrichter\/in kann jeder werden, der Lust dazu hat und mindestens 14 Jahre alt ist. Der Lehrgang ist kostenfrei. Bei Interesse bitte einfach bei Michael Weber, jedem anderen Mitglied des Pr\u00e4sidiums, der Gesch\u00e4ftsstelle oder einem Trainer des TSV melden.<\/p>\n<p><strong>Wir werden regelm\u00e4\u00dfig \u00fcber das Projekt berichten.<\/strong><\/p>\n<p><em>(Bericht: Johannes Kern)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stellen Sie sich vor, es ist Sonntagmittag, Sie freuen sich darauf, in der Langenberghalle ein spannendes Handballspiel mitzuerleben und dann das: aufgrund des akuten Schiedsrichtermangels muss das Spiel ausfallen!<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[77],"tags":[],"class_list":["post-16278","post","type-post","status-publish","format-standard","hentry","category-schiedsrichter"],"_links":{"self":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/16278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/comments?post=16278"}],"version-history":[{"count":6,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/16278\/revisions"}],"predecessor-version":[{"id":16285,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/16278\/revisions\/16285"}],"wp:attachment":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/media?parent=16278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/categories?post=16278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/tags?post=16278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}