{"id":15043,"date":"2013-01-26T21:49:20","date_gmt":"2013-01-26T20:49:20","guid":{"rendered":"http:\/\/w-jugend.tsv-birkenau.de\/?p=15043"},"modified":"2013-02-13T15:55:35","modified_gmt":"2013-02-13T14:55:35","slug":"regeltest-vom-heimspieltag","status":"publish","type":"post","link":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/archives\/15043","title":{"rendered":"Zuschauer fallen bei Regeltest durch&#8230;"},"content":{"rendered":"<p><a href=\"http:\/\/w-jugend.tsv-birkenau.de\/wp-content\/upload\/TSV_GewinnspielSchiri.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-15056\" style=\"border: 1px solid black;\" title=\"TSV_GewinnspielSchiri\" src=\"http:\/\/w-jugend.tsv-birkenau.de\/wp-content\/upload\/TSV_GewinnspielSchiri.png\" alt=\"\" width=\"400\" height=\"288\" srcset=\"https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/TSV_GewinnspielSchiri.png 1000w, https:\/\/damenhandball.tsv-birkenau.de\/wp-content\/upload\/TSV_GewinnspielSchiri-300x216.png 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<p>Beim Heimspieltag am 26. Januar 2013 unter dem Motto &#8222;Im Dienste des Spiels&#8220; gab es 2x 2 Eintrittskarten f\u00fcr ein Bundesligaspiel der Flames Bensheim zu gewinnen. Dabei galt es, den oben stehenden Regeltest komplett richtig zu beantworten. Unter allen Einsendungen waren ingesamt nur zwei richtige dabei &#8211; ein guter Beweis daf\u00fcr, dass die Zuschauer und Fans nicht in das Wissen eines Schiedsrichter haben und sich das ein oder andere Mal bei einer Entscheidung des Schiedsrichters auf dem Spielfeld lieber zur\u00fccknehmen sollten. Mit Klick auf das Foto k\u00f6nnt auch ihr euer Wissen testen. Die L\u00f6sungen befinden sich hier:<!--more--><\/p>\n<p><strong>L\u00d6SUNGEN:<\/strong> 1: B \/ 2: B, D \/ 3: B \/ 4: D \/ 5: B<\/p>\n<p>Wer sich das Wissen eines Schiedsrichters aneignen m\u00f6chte, kann entweder am kommenden Mittwoch (30. Januar) um 18.30 Uhr im Foyer der Langenberghalle an der Schulung f\u00fcr vereinsinterne Schiedsrichter teilnehmen oder eine Schiedsrichterausbildung beim Badischen Handballverband \/ Handballkreis Mannheim durchziehen!<\/p>\n<p><a href=\"http:\/\/handballsrmannheim.wordpress.com\/\" target=\"_blank\">Die Informationen dazu finder ihr hier<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Beim Heimspieltag am 26. Januar 2013 unter dem Motto &#8222;Im Dienste des Spiels&#8220; gab es 2x 2 Eintrittskarten f\u00fcr ein Bundesligaspiel der Flames Bensheim zu gewinnen. Dabei galt es, den oben stehenden Regeltest komplett richtig zu beantworten. Unter allen Einsendungen waren ingesamt nur zwei richtige dabei &#8211; ein guter Beweis daf\u00fcr, dass die Zuschauer und&hellip;&nbsp;<a href=\"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/archives\/15043\" rel=\"bookmark\">Weiterlesen &raquo;<span class=\"screen-reader-text\">Zuschauer fallen bei Regeltest durch&#8230;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[1,78,77],"tags":[],"class_list":["post-15043","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-heimspieltag","category-schiedsrichter"],"_links":{"self":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/15043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/comments?post=15043"}],"version-history":[{"count":15,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/15043\/revisions"}],"predecessor-version":[{"id":15362,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/posts\/15043\/revisions\/15362"}],"wp:attachment":[{"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/media?parent=15043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/categories?post=15043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/damenhandball.tsv-birkenau.de\/index.php\/wp-json\/wp\/v2\/tags?post=15043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}